{"id":6463,"date":"2025-10-22T08:41:31","date_gmt":"2025-10-21T23:41:31","guid":{"rendered":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/?p=6463"},"modified":"2025-10-22T16:42:37","modified_gmt":"2025-10-22T07:42:37","slug":"%e3%80%90%e6%b4%bb%e5%8b%95%e5%a0%b1%e5%91%8a%e3%80%91%e3%82%a4%e3%83%b3%e3%83%89%e6%b4%8b%e5%a4%a7%e6%b4%a5%e6%b3%a2%e3%81%8b%e3%82%8920%e5%b9%b4%e2%80%95%e3%82%a4%e3%83%b3%e3%83%89%e3%83%8d-2","status":"publish","type":"post","link":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/2025\/10\/6463\/","title":{"rendered":"\u3010\u6d3b\u52d5\u5831\u544a\u3011\u30a4\u30f3\u30c9\u6d0b\u5927\u6d25\u6ce2\u304b\u308920\u5e74\u2015\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u30fb\u30d0\u30f3\u30c0\u30a2\u30c1\u30a7\u306e\u4eca\uff08\u5f8c\u534a\uff09\uff5cKiDS\u9632\u707d\u6559\u80b2\u30d7\u30ed\u30b8\u30a7\u30af\u30c8 2025\u5e749\u67083\u65e5\u301c9\u670810\u65e5"},"content":{"rendered":"\n<p>\u3053\u3093\u306b\u3061\u306f\uff01\u5965\u6751\u30bc\u30df3\u56de\u751f\u306e\u91d1\u6fa4\u60a0\u6a39\u3067\u3059\u3002<br>\u79c1\u306f9\u67083\u65e5\u304b\u308910\u65e5\u307e\u3067\u3001\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u306e\u30d0\u30f3\u30c0\u30a2\u30c1\u30a7\u3067\u300cKiDS\u300d\u30e1\u30f3\u30d0\u30fc\u306e\u4e00\u54e1\u3068\u3057\u3066\u6d3b\u52d5\u306b\u53c2\u52a0\u3057\u307e\u3057\u305f\u3002\u73fe\u5730\u3067\u306f\u3001\u9632\u707d\u6559\u80b2\u306e\u5b9f\u8df5\u306b\u52a0\u3048\u3001\u6d25\u6ce2\u88ab\u707d\u5730\u306e\u5fa9\u8208\u72b6\u6cc1\u3084\u9632\u707d\u306e\u73fe\u72b6\u306b\u3064\u3044\u3066\u306e\u8abf\u67fb\u3082\u884c\u3044\u307e\u3057\u305f\u3002<br><br>\u3053\u306e\u30d6\u30ed\u30b0\u3067\u306f\uff0c\u5b50\u3069\u3082\u305f\u3061\u3068\u306e\u4ea4\u6d41\u306e\u69d8\u5b50\u3084\u73fe\u5730\u3067\u306e\u5b66\u3073\u306b\u3064\u3044\u3066\u66f8\u3044\u3066\u3044\u307e\u3059\u3002\u524d\u534a\u306b\u7d9a\u304d\u3001\u5f8c\u534a\u3082\u5b66\u3073\u3068\u611f\u52d5\u306b\u3042\u3075\u308c\u305f\u3001\u304b\u3051\u304c\u3048\u306e\u306a\u3044\u65e5\u3005\u3068\u306a\u308a\u307e\u3057\u305f\u3002\uff08\u524d\u534a\u306e\u8a18\u4e8b\u306f<a href=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/2025\/10\/6382\/\">\u3053\u3061\u3089<\/a>\uff09<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">9\u67087\u65e5\uff08\u65e5\uff09\u30a2\u30c1\u30a7\u3067\u306e \u201cChill Day\u201d<\/h4>\n\n\n\n<p>\u3053\u306e\u65e5\u306f\u65e5\u66dc\u65e5\u306a\u306e\u3067\u5c0f\u5b66\u6821\u3067\u306e\u6d3b\u52d5\u306f\u304a\u4f11\u307f\u3002\u300cChill Day\u300d\u3068\u79f0\u3057\u3066\u3001\u30a2\u30c1\u30a7\u306e\u3055\u307e\u3056\u307e\u306a\u5834\u6240\u3092\u5de1\u308a\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u671d8\u6642\u3001\u6700\u521d\u306b\u8a2a\u308c\u305f\u306e\u306f\u73fe\u5730\u306e\u6d3b\u6c17\u3042\u3075\u308c\u308b\u5e02\u5834\u3002\u9b5a\u3084\u679c\u7269\u306e\u72ec\u7279\u306a\u5302\u3044\u3068\u4eba\u3005\u306e\u8cd1\u308f\u3044\u306b\u5727\u5012\u3055\u308c\u3063\u3071\u306a\u3057\u3067\u3057\u305f\u3002\u5e02\u5834\u3092\u6b69\u3044\u3066\u3044\u308b\u3068\u3001\u306a\u3093\u3068\u30b5\u30e1\u304c\uff01\u5168\u54e1\u304c\u9a5a\u304d\u306e\u58f0\u3092\u4e0a\u3052\u3066\u3044\u307e\u3057\u305f\u3002\u307e\u305f\u3001\u5e02\u5834\u306f\u6d77\u306e\u305d\u3070\u306b\u3042\u308b\u306e\u3067\u3059\u304c\u3001\u8fd1\u304f\u306b\u9ad8\u3044\u5efa\u7269\u3084\u9ad8\u53f0\u306f\u306a\u304f\u3001\u6d25\u6ce2\u3078\u306e\u5099\u3048\u304c\u6c17\u306b\u306a\u308a\u307e\u3057\u305f\u3002\u5e02\u5834\u3092\u4e00\u901a\u308a\u898b\u3066\u56de\u3063\u305f\u5f8c\u3001\u65e5\u672c\u3078\u5148\u306b\u5e30\u56fd\u3055\u308c\u308b\u5965\u6751\u5148\u751f\u3068\u306f\u3053\u3053\u3067\u304a\u5225\u308c\u3092\u3057\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_41-1024x768.jpg\" alt=\"\" class=\"wp-image-6518\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_41-1024x768.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_41-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_41-768x576.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_41.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u5e02\u5834\u3067\u96c6\u5408\u5199\u771f\u2501\u2501\u671d\u304b\u3089\u30a2\u30af\u30c6\u30a3\u30d6\uff01<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_42-1-768x1024.jpg\" alt=\"\" class=\"wp-image-6520\" style=\"width:840px;height:auto\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_42-1-768x1024.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_42-1-225x300.jpg 225w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_42-1.jpg 1108w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">\u58f2\u3089\u308c\u3066\u3044\u305f\u30b5\u30e1<\/figcaption><\/figure>\n\n\n\n<p>\u7d9a\u3044\u3066\u3001\u79c1\u305f\u3061\u306f\u30c9\u30e9\u30b4\u30f3\u30dc\u30fc\u30c8\u306b\u4e57\u3063\u3066\u5ddd\u4e0a\u308a\u3092\u4f53\u9a13\u3002\u5cb8\u306b\u306f\u30de\u30f3\u30b0\u30ed\u30fc\u30d6\u304c\u751f\u3044\u8302\u308a\u3001\u5ddd\u3082\u7f8e\u3057\u304b\u3063\u305f\u3067\u3059\u3002\u5199\u771f\u3092\u64ae\u3063\u305f\u308a\u3001\u8db3\u3092\u6c34\u306b\u6d78\u3057\u3066\u4f11\u3093\u3060\u308a\u3001\u3042\u307e\u308a\u306e\u7f8e\u3057\u3055\u306b\u601d\u308f\u305a\u6cf3\u304e\u51fa\u3059\u4eba\u3082\u3044\u3066\u3001\u601d\u3044\u601d\u3044\u306b\u81ea\u7531\u306a\u6642\u9593\u3092\u904e\u3054\u3057\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"686\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_18-1024x686.jpg\" alt=\"\" class=\"wp-image-6510\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_18-1024x686.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_18-300x201.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_18-768x514.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_18.jpg 1277w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u7dba\u9e97\u306a\u5ddd\u3067\u306e\u96c6\u5408\u5199\u771f\u2501\u2501\u5b9f\u306f\u65e5\u672c\u3088\u308a\u6dbc\u3057\u3044\u3067\u3059\uff01<\/figcaption><\/figure>\n\n\n\n<p>\u663c\u98df\u306f\u6d77\u306b\u9762\u3057\u305f\u30a4\u30bf\u30ea\u30a2\u30f3\u30ec\u30b9\u30c8\u30e9\u30f3\u3067\u3002\u6599\u7406\u304c\u3067\u304d\u308b\u307e\u3067\u306e\u3042\u3044\u3060\u3001\u76ee\u306e\u524d\u306e\u30d3\u30fc\u30c1\u3067\u30ea\u30d5\u30ec\u30c3\u30b7\u30e5\u3057\u307e\u3057\u305f\u3002\u30a2\u30c1\u30a7\u306f\u30a4\u30f3\u30c9\u6d0b\u306b\u9762\u3057\u3066\u304a\u308a\u3001\u6ce2\u304c\u9ad8\u3044\u305f\u3081\u30b5\u30fc\u30d5\u30a1\u30fc\u306b\u3082\u4eba\u6c17\u304c\u3042\u308b\u305d\u3046\u3067\u3059\u3002\u3053\u3053\u3067\u3001\u5965\u6751\u30bc\u30dfOG\u306e\u85e4\u6728\u3055\u3093\u3068\u3082\u304a\u5225\u308c\u3092\u3057\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_39-683x1024.jpg\" alt=\"\" class=\"wp-image-6521\" style=\"width:840px;height:auto\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_39-683x1024.jpg 683w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_39-200x300.jpg 200w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_39-768x1152.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_39-1024x1536.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_39.jpg 1365w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">\u7dba\u9e97\u306a\u6d77\u3092\u80cc\u666f\u306b\u30dd\u30fc\u30ba\u2501\u2501\u5357\u56fd\u6765\u305f\u305e\u301c\uff01<\/figcaption><\/figure>\n\n\n\n<p>\u5348\u5f8c\u306f\u3001\u30b9\u30de\u30c8\u30e9\u5cf6\u6c96\u5730\u9707\u3067\u751a\u5927\u306a\u88ab\u5bb3\u3092\u53d7\u3051\u306a\u304c\u3089\u518d\u5efa\u3055\u308c\u305f\u300c\u30c8\u30eb\u30b3\u6751\u300d\u3068\u305d\u306e\u30e2\u30b9\u30af\u3092\u8a2a\u308c\u307e\u3057\u305f\u3002\u707d\u5bb3\u76f4\u5f8c\u306e\u5199\u771f\u304c\u5c55\u793a\u3055\u308c\u3066\u304a\u308a\u3001\u74e6\u792b\u306e\u4e2d\u3067\u30e2\u30b9\u30af\u3060\u3051\u304c\u6b8b\u3063\u3066\u3044\u308b\u5149\u666f\u306b\u606f\u3092\u306e\u307f\u307e\u3057\u305f\u3002\u4ed6\u306e\u30e2\u30b9\u30af\u3067\u3082\u4f3c\u305f\u3088\u3046\u306a\u5199\u771f\u304c\u5c55\u793a\u3055\u308c\u3066\u3044\u305f\u3053\u3068\u3092\u601d\u3044\u51fa\u3057\u307e\u3057\u305f\u3002\u30a2\u30c1\u30a7\u3067\u306f\u3053\u306e\u3088\u3046\u306a\u5199\u771f\u3092\u898b\u3066\u300c\u707d\u5bb3\u6642\u306b\u306f\u30e2\u30b9\u30af\u3078\u9003\u3052\u308b\u300d\u3068\u8003\u3048\u308b\u4eba\u304c\u5897\u3048\u3066\u3044\u308b\u306e\u3067\u306f\u306a\u3044\u304b\u3068\u611f\u3058\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_38-edited.jpg\" alt=\"\" class=\"wp-image-6523\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_38-edited.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_38-edited-225x300.jpg 225w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_38-edited-768x1024.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_38-edited-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><figcaption class=\"wp-element-caption\">\u30e2\u30b9\u30af\u4ee5\u5916\u304c\u6d25\u6ce2\u3067\u6d41\u3055\u308c\u305f\u753a\u3092\u30a2\u30e1\u30ea\u30ab\u8ecd\u304c\u652f\u63f4\u3057\u3066\u3044\u308b\u5199\u771f<\/figcaption><\/figure>\n\n\n\n<p>\u7d9a\u3044\u3066\u8a2a\u308c\u305f\u306e\u306f \u201cSophie\u2019s Sunset Library and Beach\u201d\u3002\u3053\u3053\u3067\u306f\u3001\u30b9\u30de\u30c8\u30e9\u5cf6\u6c96\u5730\u9707\u3092\u7d4c\u9a13\u3057\u305f\u30bd\u30d5\u30a3\u30fc\u3055\u3093\u306e\u6bcd\u89aa\u3001\u30e9\u30a4\u30cf\u30f3\u3055\u3093\u304b\u3089\u304a\u8a71\u3092\u4f3a\u3044\u307e\u3057\u305f\u3002\u5e7c\u3044\u9803\u304b\u3089\u300cSmong\uff08\u30b9\u30e2\u30f3\uff09\u300d\u3068\u3044\u3046\u6d25\u6ce2\u304b\u3089\u9003\u3052\u308b\u3053\u3068\u306e\u5927\u5207\u3055\u3092\u6559\u3048\u308b\u5b50\u5b88\u5504\u3092\u805e\u304b\u3055\u308c\u3066\u3044\u305f\u305d\u3046\u3067\u3059\u3002\u7a7a\u60f3\u3060\u3068\u601d\u3063\u3066\u3044\u305f\u305d\u306e\u5504\u304c\u73fe\u5b9f\u3068\u306a\u3063\u305f\u3068\u304d\u306e\u6050\u6016\u3001\u305d\u3057\u3066\u300c\u540c\u3058\u60b2\u5287\u3092\u7e70\u308a\u8fd4\u3055\u306a\u3044\u305f\u3081\u306b\u300d\u3068\u9632\u707d\u6559\u80b2\u306b\u5c3d\u529b\u3059\u308b\u5f7c\u5973\u306e\u59ff\u52e2\u306b\u3001\u80f8\u3092\u6253\u305f\u308c\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_37-1024x683.jpg\" alt=\"\" class=\"wp-image-6524\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_37-1024x683.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_37-300x200.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_37-768x512.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_37-1536x1024.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_37.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u6d77\u3092\u898b\u3066\u7652\u3055\u308c\u3066\u3044\u308b\u69d8\u5b50\u2501\u2501\u96f0\u56f2\u6c17\u306b\u5408\u3063\u305f\u6b4c\u3092\u6b4c\u5531\u4e2d\u301c<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_36-1024x768.jpg\" alt=\"\" class=\"wp-image-6525\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_36-1024x768.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_36-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_36-768x576.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_36.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u30e9\u30a4\u30cf\u30f3\u3055\u3093\u304b\u3089\u707d\u5bb3\u306e\u7d4c\u9a13\u8ac7\u3092\u805e\u3044\u3066\u3044\u308b\u69d8\u5b50<\/figcaption><\/figure>\n\n\n\n<p>\u591c\u306f\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u6599\u7406\u306e\u300c\u30df\u30fc\u30b4\u30ec\u30f3\u300d\u3092\u582a\u80fd\u3057\u307e\u3057\u305f\u3002\u201c\u30df\u30fc\u201d\u306f\u9eba\u3001\u201c\u30b4\u30ec\u30f3\u201d\u306f\u7092\u3081\u308b\u30fb\u63da\u3052\u308b\u3068\u3044\u3046\u610f\u5473\u3067\u3001\u7518\u8f9b\u3044\u30bd\u30fc\u30b9\u306b\u5375\u3084\u9d8f\u8089\u3001\u30a8\u30d3\u306a\u3069\u3001\u81ea\u5206\u306e\u597d\u307f\u306e\u5177\u6750\u3092\u52a0\u3048\u3066\u98df\u3079\u307e\u3057\u305f\u3002\u5c11\u3057\u305a\u3064\u73fe\u5730\u306e\u98df\u3079\u65b9\u306b\u3082\u6163\u308c\u3066\u304d\u305f\u3088\u3046\u306b\u611f\u3058\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u5915\u98df\u5f8c\u306b\u306f\u3001\u6025\u907d\u307f\u3093\u306a\u3067\u30d0\u30c9\u30df\u30f3\u30c8\u30f3\u3092\u697d\u3082\u3046\u3068\u3044\u3046\u3053\u3068\u306b\u306a\u308a\u307e\u3057\u305f\u3002\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u3067\u306f\u30b5\u30c3\u30ab\u30fc\u3068\u4e26\u3076\u4eba\u6c17\u30b9\u30dd\u30fc\u30c4\u3067\u3001\u767d\u71b1\u3057\u305f\u8a66\u5408\u306b\u3002\u672a\u7d4c\u9a13\u306e\u79c1\u306f\u30ec\u30d9\u30eb\u304c\u9055\u3044\u3059\u304e\u3066\u624b\u3082\u8db3\u3082\u51fa\u307e\u305b\u3093\u3067\u3057\u305f\u3002\u305b\u3081\u3066\u30b7\u30e3\u30c8\u30eb\u3092\u8fd4\u305b\u308b\u3060\u3051\u306e\u8155\u304c\u3042\u308c\u3070\u3068\u3001\u6094\u3057\u3055\u534a\u5206\u3001\u697d\u3057\u3055\u534a\u5206\u306e\u3072\u3068\u3068\u304d\u3067\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_35-1024x768.jpg\" alt=\"\" class=\"wp-image-6526\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_35-1024x768.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_35-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_35-768x576.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_35-1536x1152.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_35.jpg 1796w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u306e\u30e1\u30f3\u30d0\u30fc\u3068\u30d0\u30c8\u30df\u30f3\u30c8\u30f3\u3067\u4ea4\u6d41\u2501\u2501\u5fc3\u3082\u4f53\u3082\u30db\u30c3\u30c8\u306b\uff01<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">9\u67088\u65e5\uff08\u6708\uff09\u5b66\u3073\u3092\u6df1\u3081\u308b\u4ea4\u6d41<\/h4>\n\n\n\n<p>\u5348\u524d\u4e2d\u306f\u3001\u30a4\u30f3\u30bf\u30fc\u30ca\u30b7\u30e7\u30ca\u30eb\u30b9\u30af\u30fc\u30eb\u3068\u30cd\u30a4\u30c1\u30e3\u30fc\u30b9\u30af\u30fc\u30eb\u306e2\u6821\u3092\u8a2a\u554f\u3057\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u30a4\u30f3\u30bf\u30fc\u30ca\u30b7\u30e7\u30ca\u30eb\u30b9\u30af\u30fc\u30eb\u3067\u306f\u3001\u5b50\u3069\u3082\u305f\u3061\u304c\u7af9\u306e\u697d\u5668\u300c\u30a2\u30f3\u30af\u30eb\u30f3\u300d\u3068\u6b4c\u3067\u6e29\u304b\u304f\u8fce\u3048\u3066\u304f\u308c\u307e\u3057\u305f\u3002\u305d\u306e\u97f3\u8272\u306f\u5fc3\u306b\u97ff\u304d\u3001\u672c\u5f53\u306b\u611f\u52d5\u3057\u307e\u3057\u305f\u3002\u5287\u306e\u5f8c\u306b\u306f\u3001\u79c1\u305f\u3061\u306f\u5b50\u3069\u3082\u305f\u3061\u306b\u300c\u4f55\u3092\u5b66\u3073\u3001\u8ab0\u306b\u4f1d\u3048\u308b\u306e\u304b\u300d\u3068\u3044\u3046\u554f\u3044\u3092\u6295\u3052\u304b\u3051\u3001\u5b50\u3069\u3082\u305f\u3061\u306e\u4e3b\u4f53\u7684\u306a\u5b66\u3073\u3092\u4fc3\u3059\u3053\u3068\u304c\u3067\u304d\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1782\" height=\"1188\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_34-edited.jpg\" alt=\"\" class=\"wp-image-6528\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_34-edited.jpg 1782w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_34-edited-300x200.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_34-edited-1024x683.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_34-edited-768x512.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_34-edited-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1782px) 100vw, 1782px\" \/><figcaption class=\"wp-element-caption\">\u30a4\u30f3\u30bf\u30fc\u30ca\u30b7\u30e7\u30ca\u30eb\u30b9\u30af\u30fc\u30eb\u3067\u96c6\u5408\u5199\u771f\u2501\u2501\u306e\u3073\u592a\u304f\u3093\u3092\u63a2\u305b\uff01<\/figcaption><\/figure>\n\n\n\n<p>\u30cd\u30a4\u30c1\u30e3\u30fc\u30b9\u30af\u30fc\u30eb\u306f\u3001\u96fb\u6c17\u3082\u7a93\u3082\u306a\u3044\u958b\u653e\u7684\u306a\u5b66\u6821\u3067\u3057\u305f\u3002\u7d19\u306e\u6559\u79d1\u66f8\u3092\u307b\u3068\u3093\u3069\u4f7f\u308f\u305a\u3001\u79c1\u305f\u3061\u306e\u3088\u3046\u306a\u5916\u90e8\u306e\u4eba\u3068\u306e\u4ea4\u6d41\u3092\u901a\u3057\u3066\u5b66\u3073\u3092\u6df1\u3081\u3066\u3044\u308b\u305d\u3046\u3067\u3059\u3002\u3053\u306e\u5b66\u6821\u3067\u306f\u5168\u5b66\u5e74\u304c\u53c2\u52a0\u3057\u3066\u304f\u308c\u305f\u306e\u3067\u3001\u3053\u308c\u307e\u3067\u8a2a\u554f\u3057\u305f\u5b66\u6821\u3068\u306f\u5c11\u3057\u9055\u3063\u305f\u96f0\u56f2\u6c17\u3092\u697d\u3057\u307f\u306a\u3089\u304c\u6d3b\u52d5\u3067\u304d\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_33-1024x769.jpg\" alt=\"\" class=\"wp-image-6529\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_33-1024x769.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_33-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_33-768x577.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_33-1536x1154.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_33.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u30cd\u30a4\u30c1\u30e3\u30fc\u30b9\u30af\u30fc\u30eb\u3067\u96c6\u5408\u5199\u771f\u2501\u2501\u30c9\u30e9\u3048\u3082\u3093\u305f\u3061\u3082\u5927\u4eba\u6c17\uff01<\/figcaption><\/figure>\n\n\n\n<p>\u5348\u5f8c\u306f\u30b7\u30e3\u30af\u30a2\u30e9\u5927\u5b66\u3078\u3002KiDS\u30d7\u30ed\u30b8\u30a7\u30af\u30c8\u306e\u5275\u8a2d\u8005\u3067\u3042\u308b\u6e05\u91ce\u540d\u8a89\u6559\u6388\u304c\u8b1b\u6f14\u3092\u884c\u3044\u30012004\u5e74\u30b9\u30de\u30c8\u30e9\u5cf6\u6c96\u5730\u9707\u30682011\u5e74\u6771\u65e5\u672c\u5927\u9707\u707d\u306e\u5171\u901a\u70b9\u3092\u6319\u3052\u306a\u304c\u3089\u3001\u30cf\u30fc\u30c9\u5bfe\u7b56\u3060\u3051\u3067\u306a\u304f\u300c\u4eba\u306e\u9632\u707d\u884c\u52d5\u3092\u4fc3\u3059\u30bd\u30d5\u30c8\u5bfe\u7b56\u300d\u306e\u91cd\u8981\u6027\u3092\u8a9e\u3089\u308c\u307e\u3057\u305f\u3002\u751a\u5927\u306a\u6d25\u6ce2\u707d\u5bb3\u3092\u7d4c\u9a13\u3057\u3001\u5c06\u6765\u306e\u5927\u304d\u306a\u6d25\u6ce2\u707d\u5bb3\u306b\u5099\u3048\u3066\u3044\u308b\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u3068\u65e5\u672c\u306e\u4e21\u56fd\u304c\u3001\u7d4c\u9a13\u3092\u5171\u6709\u3057\u3001\u4e92\u3044\u306e\u77e5\u898b\u3092\u751f\u304b\u3059\u3053\u3068\u304c\u3067\u304d\u308c\u3070\u3001\u6d25\u6ce2\u9632\u707d\u3092\u3055\u3089\u306b\u524d\u9032\u3055\u305b\u308b\u3053\u3068\u304c\u3067\u304d\u308b\u3068\u611f\u3058\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_32-1024x769.jpg\" alt=\"\" class=\"wp-image-6530\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_32-1024x769.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_32-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_32-768x577.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_32-1536x1154.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_32.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u30b7\u30e3\u30af\u30a2\u30e9\u5927\u5b66\u3067KiDS\u306e\u201cK\u201d\u30dd\u30fc\u30ba<\/figcaption><\/figure>\n\n\n\n<p>\u7d9a\u3044\u3066\u8a2a\u308c\u305f\u3001TDMRC\uff08Tsunami Disaster Mitigation &amp; Research Center\uff09\u306f\u30012004\u5e74\u30b9\u30de\u30c8\u30e9\u5cf6\u6c96\u5730\u9707\u5f8c\u306b\u8a2d\u7acb\u3055\u308c\u305f\u6d25\u6ce2\u9632\u707d\u7814\u7a76\u306e\u62e0\u70b9\u3067\u3059\u3002\u65e5\u672c\u3092\u542b\u3080\u56fd\u5185\u5916\u306e\u7814\u7a76\u6a5f\u95a2\u306e\u652f\u63f4\u306e\u3082\u3068\u3067\u8a95\u751f\u3057\u305f\u306e\u3060\u305d\u3046\u3067\u3059\u3002\u300c\u79d1\u5b66\u3092\u4f1d\u3048\u3001\u30ec\u30b8\u30ea\u30a8\u30f3\u30b9\u3092\u9ad8\u3081\u308b\u300d\u3068\u3044\u3046\u7406\u5ff5\u306e\u3082\u3068\u3001\u7814\u7a76\u3092\u5730\u57df\u793e\u4f1a\u306e\u529b\u306b\u3064\u306a\u3052\u3088\u3046\u3068\u3057\u3066\u3044\u308b\u59ff\u52e2\u304c\u5370\u8c61\u7684\u3067\u3057\u305f\u3002\u73fe\u5728\u3067\u306f\u30a4\u30f3\u30c9\u6d0b\u5730\u57df\u306e\u6d25\u6ce2\u707d\u5bb3\u533b\u7642\u7814\u7a76\u306e\u62e0\u70b9\u306b\u306a\u3063\u3066\u304a\u308a\u3001\u5730\u57df\u5185\u5916\u306e\u6a5f\u95a2\u3084\u5927\u5b66\u3068\u306e\u9023\u643a\u3092\u8f2a\u3092\u5e83\u3052\u3066\u3044\u308b\u305d\u3046\u3067\u3059\u3002<\/p>\n\n\n\n<p>\u305d\u306e\u7406\u5ff5\u306e\u5b9f\u73fe\u3059\u308b\u305f\u3081\u306b\u3001\u6bce\u5e74\u3001\u300c\u707d\u5bb3\u30ea\u30b9\u30af\u8efd\u6e1b\u300d\u3092\u30c6\u30fc\u30de\u306b\u3057\u305f\u56fd\u969b\u30b3\u30f3\u30da\uff08\u5927\u5b66\u306e\u5b66\u90e8\u751f\u5bfe\u8c61\uff09\u3092\u958b\u50ac\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u4eca\u56de\u3001\u79c1\u305f\u3061\u3082\u53c2\u52a0\u3092\u547c\u3073\u304b\u3051\u3066\u3044\u305f\u3060\u304d\u307e\u3057\u305f\u3002\u5e30\u56fd\u5f8c\u3001KiDS\u30e1\u30f3\u30d0\u30fc\u3067\u3042\u308b\u4eac\u90fd\u5927\u5b66\u306e\u5b66\u751f\u3068\u5354\u529b\u3057\u5408\u3044\u300c\u707d\u5bb3\u60c5\u5831\u306b\u5bfe\u3059\u308b\u4eba\u3005\u306e\u5e0c\u8584\u5316\u300d\u306b\u95a2\u3059\u308b\u5c0f\u8ad6\u6587\u3092\u57f7\u7b46\u3057\u3001\u30a8\u30f3\u30c8\u30ea\u30fc\u3057\u307e\u3057\u305f\u3002\u73fe\u5728\u3001\u30d5\u30a1\u30a4\u30ca\u30eb\u9078\u8003\u306b\u99d2\u3092\u9032\u3081\u3066\u3044\u307e\u3059\u3002\u7d50\u679c\u306f\u5f8c\u65e5\u5831\u544a\u3057\u305f\u3044\u3068\u601d\u3044\u307e\u3059\u3002\u56fd\u969b\u30b3\u30f3\u30da\u3078\u306e\u53c2\u52a0\u306f\u307e\u3063\u305f\u304f\u4e88\u5b9a\u3057\u3066\u3044\u306a\u304b\u3063\u305f\u3053\u3068\u3067\u3057\u305f\u304c\u3001\u65e5\u672c\u3068\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u306b\u5171\u901a\u3059\u308b\u554f\u984c\u3092\u8003\u3048\u3001KiDS\u306e\u6d3b\u52d5\u3092\u898b\u3064\u3081\u76f4\u3059\u826f\u3044\u6a5f\u4f1a\u306b\u306a\u308a\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_31-1024x769.jpg\" alt=\"\" class=\"wp-image-6531\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_31-1024x769.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_31-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_31-768x577.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_31-1536x1154.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_31.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">TDMRC\uff08Tsunami Disaster Mitigation &amp; Research Center\uff09\u3067\u610f\u898b\u4ea4\u63db\u2501\u2501\u30b3\u30f3\u30da\u30c6\u30a3\u30b7\u30e7\u30f3\u306b\u6025\u907d\u53c2\u52a0\uff01<\/figcaption><\/figure>\n\n\n\n<p>\u30b7\u30e3\u30af\u30a2\u30e9\u5927\u5b66\u306eOIA\uff08Office of International Affairs\uff09\u3067\u306f\u3001\u6240\u9577\u306eMuzailin\u5148\u751f\u3068\u610f\u898b\u4ea4\u63db\u3092\u884c\u3044\u307e\u3057\u305f\u3002\u65e5\u672c\u3068\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u306e\u707d\u5bb3\u6587\u5316\u306e\u9055\u3044\u3092\u8a8d\u3081\u5408\u3044\u3001\u4e92\u3044\u306b\u88dc\u3044\u5408\u3044\u306a\u304c\u3089\u767a\u5c55\u3057\u3066\u3044\u304f\u2015\u2015\u305d\u306e\u8003\u3048\u306b\u5171\u611f\u3057\u3001\u79c1\u305f\u3061\u306e\u6d3b\u52d5\u3082\u305d\u306e\u4e00\u7aef\u3092\u62c5\u3063\u3066\u3044\u308b\u306e\u3060\u3068\u611f\u3058\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_30-1024x769.jpg\" alt=\"\" class=\"wp-image-6532\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_30-1024x769.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_30-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_30-768x577.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_30-1536x1154.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_30.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u30b7\u30e3\u30af\u30a2\u30e9\u5927\u5b66\u306eOIA\uff08Office of International Affairs\uff09\u3067\u610f\u898b\u4ea4\u63db\u2501\u2501\u4e21\u56fd\u306e\u9632\u707d\u3092\u719f\u8003\u3057\u3066\u3044\u307e\u3059\uff01<\/figcaption><\/figure>\n\n\n\n<p>\u591c\u306f\u30a2\u30c1\u30a7\u3067\u306e\u6700\u5f8c\u306e\u5915\u98df\u3002\u30a2\u30c1\u30a7\u4f1d\u7d71\u6b66\u8853\u306e\u62ab\u9732\u3084\u30ae\u30bf\u30fc\u306e\u5f3e\u304d\u8a9e\u308a\u306a\u3069\u3001\u73fe\u5730\u306e\u65b9\u3005\u306e\u6e29\u304b\u3044\u3082\u3066\u306a\u3057\u306b\u80f8\u304c\u71b1\u304f\u306a\u308a\u307e\u3057\u305f\u3002\u5171\u306b\u904e\u3054\u3059\u6642\u9593\u304c\u6b8b\u308a\u308f\u305a\u304b\u3067\u3042\u308b\u3053\u3068\u3092\u5b9f\u611f\u3057\u3001\u5225\u308c\u306e\u5bc2\u3057\u3055\u304c\u8fbc\u307f\u4e0a\u3052\u3066\u304d\u307e\u3057\u305f\u304c\u3001\u305d\u306e\u3088\u3046\u306a\u95a2\u4fc2\u3092\u7bc9\u304f\u3053\u3068\u304c\u3067\u304d\u305f\u3053\u3068\u306b\u611f\u8b1d\u306e\u6c17\u6301\u3061\u3067\u3044\u3063\u3071\u3044\u3067\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_29-1024x768.jpg\" alt=\"\" class=\"wp-image-6533\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_29-1024x768.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_29-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_29-768x576.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_29.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u611f\u8b1d\u306eFarewell Dinner\u2501\u2501\u305f\u304f\u3055\u3093\u306e\u8d08\u308a\u7269\u3092\u3044\u305f\u3060\u304d\u307e\u3057\u305f\uff01<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">9\u67089\u65e5\uff08\u706b\uff09\u30a2\u30c1\u30a7\u6700\u7d42\u65e5<\/h4>\n\n\n\n<p>KiDS 2025 \u3068\u3057\u3066\u904e\u3054\u3059\u6700\u5f8c\u306e\u65e5\u3002<\/p>\n\n\n\n<p>\u5348\u524d\u4e2d\u306f5\u6821\u76ee\u3068\u306a\u308b\u30a4\u30b9\u30e9\u30e0\u6559\u306e\u5c0f\u5b66\u6821\u3067\u9632\u707d\u5287\u3092\u62ab\u9732\u3057\u307e\u3057\u305f\u3002\u4f1a\u5834\u306f\u3053\u308c\u307e\u3067\u306e\u5b66\u6821\u3067\u4e00\u756a\u5e83\u304f\u3001\u4f1a\u5834\u5168\u4f53\u3092\u8d70\u308a\u56de\u3063\u305f\u308a\u3059\u308b\u306a\u3069\u306e\u30a2\u30c9\u30ea\u30d6\u3092\u52a0\u3048\u306a\u304c\u3089\u697d\u3057\u3093\u3067\u6f14\u3058\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_28-1024x683.jpg\" alt=\"\" class=\"wp-image-6535\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_28-1024x683.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_28-300x200.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_28-768x512.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_28-1536x1024.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_28.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u6700\u5f8c\u306e\u5c0f\u5b66\u6821\u3067\u9632\u707d\u5287\u3092\u3057\u3066\u3044\u308b\u69d8\u5b50\u2501\u2501\u7dca\u5f35\u305b\u305a\u306b\u697d\u3057\u3093\u3067\u3044\u307e\u3059\uff01<\/figcaption><\/figure>\n\n\n\n<p>\u305d\u306e\u5f8c\u3001ANRI\uff08\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u5171\u548c\u56fd\u56fd\u7acb\u30a2\u30fc\u30ab\u30a4\u30d6\uff09\u3092\u8a2a\u554f\u3002\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u56fd\u5bb6\u306e\u8a18\u9332\u7ba1\u7406\u3092\u884c\u3046\u653f\u5e9c\u306e\u65bd\u8a2d\u3067\u3001\u30b8\u30e3\u30ab\u30eb\u30bf\u3068\u30a2\u30c1\u30a7\u306e2\u7b87\u6240\u306b\u8a2d\u7f6e\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u79c1\u305f\u3061\u306f\u707d\u5bb3\u306b\u95a2\u3059\u308b\u884c\u653f\u6587\u66f8\u306e\u4fdd\u7ba1\u65b9\u6cd5\u306b\u3064\u3044\u3066\u89e3\u8aac\u3044\u305f\u3060\u304d\u3001\u307e\u305f\u30b9\u30de\u30c8\u30e9\u6c96\u5730\u9707\u306e\u6620\u50cf\u8a18\u9332\u306a\u3069\u3092\u898b\u305b\u3066\u3044\u305f\u3060\u304d\u307e\u3057\u305f\u3002\u3053\u3053\u3067\u306f\u707d\u5bb3\u306e\u8a18\u9332\u3092\u672a\u6765\u306b\u4f1d\u3048\u308b\u4ed5\u7d44\u307f\u306e\u5927\u5207\u3055\u3092\u5b9f\u611f\u3057\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_27-1024x576.jpg\" alt=\"\" class=\"wp-image-6536\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_27-1024x576.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_27-300x169.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_27-768x432.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_27-1536x864.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_27-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">ANRI\u306e\u8aac\u660e\u3092\u805e\u3044\u3066\u3044\u308b\u69d8\u5b50<\/figcaption><\/figure>\n\n\n\n<p>\u6700\u5f8c\u306e\u30e9\u30f3\u30c1\u3067\u306f\u3001\u5168\u54e1\u3067\u300c\u624b\u98df\u300d\u306b\u6311\u6226\u3002\u6700\u521d\u306f\u82e6\u6226\u3057\u306a\u304c\u3089\u3082\u30b3\u30c4\u3092\u6559\u308f\u308a\u3001\u6b21\u7b2c\u306b\u4e0a\u624b\u306b\u98df\u3079\u3089\u308c\u308b\u3088\u3046\u306b\u306a\u308a\u307e\u3057\u305f\u3002\u6307\u3067\u3064\u304b\u3080\u611f\u899a\u3068\u98df\u6750\u306e\u6e29\u3082\u308a\u304c\u3001\u98df\u4e8b\u3092\u3088\u308a\u8c4a\u304b\u306b\u3057\u3066\u304f\u308c\u308b\u3088\u3046\u3067\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_26-1024x683.jpg\" alt=\"\" class=\"wp-image-6537\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_26-1024x683.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_26-300x200.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_26-768x512.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_26-1536x1024.jpg 1536w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_26.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u30a2\u30c1\u30a7\u3067\u307f\u3093\u306a\u3068\u6700\u5f8c\u306e\u98df\u4e8b\u2501\u2501\u624b\u98df\u306b\u6311\u6226\uff01<\/figcaption><\/figure>\n\n\n\n<p>\u7a7a\u6e2f\u3067\u306f\u3001\u5225\u308c\u3092\u60dc\u3057\u3080\u58f0\u3068\u6d99\u304c\u3042\u3075\u308c\u307e\u3057\u305f\u3002\u8a18\u5ff5\u5199\u771f\u3092\u64ae\u308a\u3001\u611f\u8b1d\u3092\u4f1d\u3048\u5408\u3044\u306a\u304c\u3089\u3001\u30a2\u30c1\u30a7\u3067\u904e\u3054\u3057\u305f\u65e5\u3005\u306e\u5c0a\u3055\u3092\u565b\u307f\u3057\u3081\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_25-1024x768.jpg\" alt=\"\" class=\"wp-image-6538\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_25-1024x768.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_25-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_25-768x576.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_25.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u7a7a\u6e2f\u3067\u611f\u8b1d\u3068\u6d99\u306e\u304a\u5225\u308c\u2501\u2501\u5fd8\u308c\u3089\u308c\u306a\u3044\u601d\u3044\u51fa\uff01<\/figcaption><\/figure>\n\n\n\n<p>\u7d4c\u7531\u5730\u3067\u3042\u308b\u30b8\u30e3\u30ab\u30eb\u30bf\u7a7a\u6e2f\u306b\u5230\u7740\u3057\u305f\u79c1\u305f\u3061\u306f\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u6599\u7406\u3068KFC\u3092\u98df\u3079\u307e\u3057\u305f\u3002\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u306e\u30c1\u30ad\u30f3\u306f\u65e5\u672c\u3088\u308a\u6cb9\u304c\u3055\u3063\u3071\u308a\u3057\u3066\u3044\u3066\u3001\u98df\u611f\u3082\u30af\u30ea\u30b9\u30d4\u30fc\u3067\u3057\u305f\u3002\u56fd\u306b\u3088\u3063\u3066\u5473\u304c\u5909\u308f\u308b\u3053\u3068\u3092\u77e5\u308c\u3066\u826f\u3044\u7d4c\u9a13\u3092\u3059\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_23-1024x768.jpg\" alt=\"\" class=\"wp-image-6539\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_23-1024x768.jpg 1024w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_23-300x225.jpg 300w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_23-768x576.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_23.jpg 1477w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u7a7a\u6e2f\u3067\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u6599\u7406\u3092\u582a\u80fd<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">9\u670810\u65e5\uff08\u6c34\uff09\u65e5\u672c\u3078\u5e30\u56fd<\/h4>\n\n\n\n<p>2\u3064\u76ee\u306e\u7d4c\u7531\u5730\u3067\u3042\u308b\u30b7\u30f3\u30ac\u30dd\u30fc\u30eb\u30fb\u30c1\u30e3\u30f3\u30ae\u56fd\u969b\u7a7a\u6e2f\u3067\u306f\u5c11\u3057\u6642\u9593\u304c\u3042\u3063\u305f\u306e\u3067\u3001\u7686\u3001\u7a7a\u6e2f\u5185\u3092\u6563\u7b56\u3059\u308b\u306a\u3069\u3057\u3066\u3001\u601d\u3044\u601d\u3044\u306b\u904e\u3054\u3057\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_22-768x1024.jpg\" alt=\"\" class=\"wp-image-6540\" style=\"width:840px;height:auto\" srcset=\"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_22-768x1024.jpg 768w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_22-225x300.jpg 225w, https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-content\/uploads\/sites\/73\/2025\/10\/LINE_ALBUM_KiDS\u6d3b\u52d5\u5831\u544a\u7528\u5199\u771f_251022_22.jpg 1108w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">\u7a7a\u6e2f\u306e\u5674\u6c34\u524d\u3067Singapore\u306e\u201cS\u201d\u2501\u2501\u5674\u6c34\u306b\u65e5\u5149\u304c\u5dee\u3057\u795e\u79d8\u7684\u306b<\/figcaption><\/figure>\n\n\n\n<p>\u95a2\u7a7a\u306b\u5230\u7740\u5f8c\u3001\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u5074\u306e\u5b66\u751f\u305f\u3061\u3068\u30d3\u30c7\u30aa\u901a\u8a71\u3092\u3057\u5e30\u56fd\u3092\u5831\u544a\u3057\u307e\u3057\u305f\u3002\u6700\u5f8c\u306e\u77ac\u9593\u307e\u3067\u5fc3\u6e29\u307e\u308b\u6642\u9593\u3092\u904e\u3054\u3059\u3053\u3068\u304c\u3067\u304d\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u6d3b\u52d5\u3092\u7d42\u3048\u3066\uff08\u91d1\u6fa4\uff09<\/h4>\n\n\n\n<p>\u4eca\u56de\u306e\u6d3b\u52d5\u306b\u53c2\u52a0\u3057\u3066\u3001\u73fe\u5730\u3092\u8a2a\u308c\u308b\u3053\u3068\u3084\u4eba\u3068\u51fa\u4f1a\u3046\u3053\u3068\u306e\u5927\u5207\u3055\u3092\u6539\u3081\u3066\u611f\u3058\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u79c1\u306fKiDS\u306e\u6d3b\u52d5\u306b\u53c2\u52a0\u3059\u308b\u307e\u3067\u3001\u30d0\u30f3\u30c0\u30fb\u30a2\u30c1\u30a7\u306e\u3053\u3068\u3092\u307e\u3063\u305f\u304f\u77e5\u308a\u307e\u305b\u3093\u3067\u3057\u305f\u3002\u3057\u304b\u3057\u3001\u904e\u53bb\u306b\u4f55\u5ea6\u3082\u5927\u304d\u306a\u707d\u5bb3\u3092\u7d4c\u9a13\u3057\u3066\u304d\u305f\u3053\u3068\u3001\u305d\u3057\u3066\u540c\u3058\u60b2\u5287\u3092\u7e70\u308a\u8fd4\u3055\u306a\u3044\u305f\u3081\u306b\u5c11\u3057\u305a\u3064\u9632\u707d\u3092\u9032\u3081\u3066\u3044\u308b\u3053\u3068\u3092\u77e5\u308a\u307e\u3057\u305f\u3002\u3055\u3089\u306b\u30012004\u5e74\u30b9\u30de\u30c8\u30e9\u5cf6\u6c96\u5730\u9707\u306e\u524d\u5f8c\u306b\u751f\u307e\u308c\u305f\u540c\u4e16\u4ee3\u306e\u5b66\u751f\u305f\u3061\u3068\u4ea4\u6d41\u3059\u308b\u4e2d\u3067\u3001\u300c\u6b21\u306b\u518d\u3073\u4f1a\u3046\u3068\u304d\u3001\u3069\u3061\u3089\u304b\u306e\u65e5\u5e38\u304c\u596a\u308f\u308c\u3066\u3044\u308b\u304b\u3082\u3057\u308c\u306a\u3044\u300d\u3068\u8003\u3048\u308b\u307b\u3069\u3001\u73fe\u5730\u306b\u884c\u304b\u306a\u3051\u308c\u3070\u5f97\u3089\u308c\u306a\u3044\u8cb4\u91cd\u306a\u7d4c\u9a13\u3092\u3059\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u6700\u5f8c\u306b\u306a\u308a\u307e\u3059\u304c\u3001\u4eca\u56de\u306e\u6d3b\u52d5\u3092\u73fe\u5730\u3067\u3054\u652f\u63f4\u304f\u3060\u3055\u3063\u305fRusnardi\u5148\u751f\u3001Wina\u3055\u3093\u3092\u306f\u3058\u3081\u3001\u30b7\u30e3\u30af\u30a2\u30e9\u5927\u5b66\u306e\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u306e\u7686\u3055\u307e\u3001\u305d\u3057\u3066\u6e05\u91ce\u5148\u751f\u30fb\u5965\u6751\u5148\u751f\u3092\u306f\u3058\u3081\u5171\u306b\u6d3b\u52d5\u3057\u305fKiDS\u30e1\u30f3\u30d0\u30fc\u306e\u7686\u3055\u307e\u3092\u542b\u3081\u3001\u95a2\u308f\u3063\u3066\u304f\u3060\u3055\u3063\u305f\u3059\u3079\u3066\u306e\u65b9\u3005\u306b\u5fc3\u3088\u308a\u611f\u8b1d\u7533\u3057\u4e0a\u3052\u307e\u3059\u3002<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u521d\u3081\u3066\u306e\u6d77\u5916\u3001KiDS \u306e\u4e00\u54e1\u3068\u3057\u3066\uff08\u5185\u6d77\uff09<\/h4>\n\n\n\n<p>\u521d\u3081\u3066\u306e\u6d77\u5916\u306f\u3001\u65c5\u884c\u3067\u306f\u306a\u304f KiDS \u306e\u6d3b\u52d5\u3067\u3057\u305f\u3002<br>\u30a2\u30c1\u30a7\u3067\u306e\u65e5\u3005\u306f\u3001\u5b50\u3069\u3082\u305f\u3061\u3078\u306e\u9632\u707d\u6559\u80b2\u3092\u306f\u3058\u3081\u3001\u5730\u57df\u306e\u4eba\u3005\u3068\u306e\u4ea4\u6d41\u3084\u81ea\u7136\u74b0\u5883\u306b\u95a2\u308f\u308b\u6d3b\u52d5\u306a\u3069\u3001\u591a\u5f69\u306a\u53d6\u308a\u7d44\u307f\u306b\u6e80\u3061\u3066\u3044\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u5c0f\u5b66\u6821\u3067\u306e\u6d3b\u52d5\u3067\u306f\u3001\u7dca\u5f35\u3057\u306a\u304c\u3089\u3082\u30a4\u30f3\u30c9\u30cd\u30b7\u30a2\u8a9e\u3067\u300c\u5730\u9707\u304c\u8d77\u304d\u305f\u3068\u304d\u306f\u3069\u3046\u52d5\u3051\u3070\u3088\u3044\u304b\u300d\u3092\u4f1d\u3048\u307e\u3057\u305f\u3002\u6163\u308c\u306a\u3044\u8a00\u8449\u306b\u6238\u60d1\u3046\u3053\u3068\u3082\u3042\u308a\u307e\u3057\u305f\u304c\u3001\u5b50\u3069\u3082\u305f\u3061\u306f\u4e00\u751f\u61f8\u547d\u8033\u3092\u50be\u3051\u3001\u5143\u6c17\u306b\u907f\u96e3\u884c\u52d5\u3078\u306e\u7406\u89e3\u3092\u793a\u3057\u3066\u304f\u308c\u307e\u3057\u305f\u3002\u305d\u306e\u771f\u5263\u306a\u773c\u5dee\u3057\u3084\u5c48\u8a17\u306e\u306a\u3044\u7b11\u9854\u306b\u89e6\u308c\u3001\u8a00\u8449\u304c\u5b8c\u5168\u306b\u901a\u3058\u306a\u304f\u3066\u3082\u3001\u4f1d\u3048\u3088\u3046\u3068\u3059\u308b\u52aa\u529b\u3084\u601d\u3044\u306f\u5fc5\u305a\u76f8\u624b\u306b\u5c4a\u304f\u3053\u3068\u3092\u5b9f\u611f\u3057\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u5730\u57df\u306e\u4eba\u3005\u3068\u306e\u5bfe\u8a71\u3067\u306f\u3001\u300c\u6d25\u6ce2\u306e\u3068\u304d\u306f\u3053\u3046\u9003\u3052\u305f\u300d\u300c\u5468\u56f2\u3068\u3053\u3046\u52a9\u3051\u5408\u3063\u305f\u300d\u3068\u3044\u3063\u305f\u751f\u306e\u58f0\u3092\u805e\u304f\u3053\u3068\u304c\u3067\u304d\u307e\u3057\u305f\u3002\u9632\u707d\u306f\u5c02\u9580\u5bb6\u3084\u884c\u653f\u3060\u3051\u306e\u3082\u306e\u3067\u306f\u306a\u304f\u3001\u66ae\u3089\u3057\u306e\u4e2d\u3067\u4e00\u4eba\u3072\u3068\u308a\u304c\u62c5\u3063\u3066\u3044\u308b\u3068\u3044\u3046\u3053\u3068\u3092\u5f37\u304f\u611f\u3058\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u6d3b\u52d5\u306e\u3042\u3044\u3060\u3001\u73fe\u5730\u306e\u5927\u5b66\u751f\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3084\u591a\u304f\u306e\u65b9\u3005\u304c\u79c1\u305f\u3061\u3092\u652f\u3048\u3066\u304f\u3060\u3055\u308a\u3001\u8a00\u8a9e\u3084\u74b0\u5883\u306e\u9055\u3044\u306b\u3088\u308b\u56f0\u96e3\u3082\u6700\u5c0f\u9650\u306b\u6291\u3048\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3057\u305f\u3002\u305d\u306e\u304a\u304b\u3052\u3067\u3001\u5b89\u5fc3\u3057\u3066\u6d3b\u52d5\u306b\u96c6\u4e2d\u3059\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3057\u305f\u3002<\/p>\n\n\n\n<p>\u3053\u3046\u3057\u305f\u4e00\u3064\u3072\u3068\u3064\u306e\u7d4c\u9a13\u306f\u3001\u79c1\u306b\u3068\u3063\u3066\u5358\u306a\u308b\u6d77\u5916\u4f53\u9a13\u3067\u306f\u3042\u308a\u307e\u305b\u3093\u3067\u3057\u305f\u3002\u9632\u707d\u3092\u300c\u77e5\u8b58\u300d\u3068\u3057\u3066\u3060\u3051\u3067\u306a\u304f\u3001\u300c\u5b9f\u8df5\u300d\u3068\u3057\u3066\u6349\u3048\u308b\u539f\u70b9\u306b\u3082\u306a\u308a\u307e\u3057\u305f\u3002\u30a2\u30c1\u30a7\u3067\u306e KiDS \u306e\u53d6\u308a\u7d44\u307f\u3092\u901a\u3057\u3066\u3001\u79c1\u306f\u4e8c\u5ea6\u3068\u30b9\u30de\u30c8\u30e9\u6c96\u5730\u9707\u306e\u3088\u3046\u306a\u88ab\u5bb3\u3092\u7e70\u308a\u8fd4\u3057\u3066\u306f\u306a\u3089\u306a\u3044\u3068\u5f37\u304f\u611f\u3058\u307e\u3057\u305f\u3002\u305d\u3057\u3066\u3001\u3053\u306e\u7d4c\u9a13\u304c\u3001\u4eca\u5f8c\u81ea\u5206\u304c\u9632\u707d\u3068\u3069\u3046\u5411\u304d\u5408\u3044\u3001\u3069\u306e\u3088\u3046\u306b\u884c\u52d5\u3057\u3066\u3044\u304f\u304b\u3092\u8003\u3048\u308b\u5927\u304d\u306a\u304d\u3063\u304b\u3051\u306b\u306a\u3063\u305f\u3068\u611f\u3058\u3066\u3044\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u6700\u5f8c\u306b\u3001\u3053\u306e\u6d3b\u52d5\u3092\u652f\u3048\u3066\u304f\u3060\u3055\u3063\u305f\u73fe\u5730\u306e\u5927\u5b66\u751f\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u3084\u5148\u751f\u65b9\u3001\u305d\u3057\u3066\u4ee3\u8868\u306e\u3068\u3082\u3055\u3093\uff08\u4e0a\u7530\u3055\u3093\uff09\u3092\u306f\u3058\u3081\u3001KiDS \u30e1\u30f3\u30d0\u30fc\u306e\u7686\u3055\u3093\u306b\u5fc3\u3088\u308a\u611f\u8b1d\u7533\u3057\u4e0a\u3052\u307e\u3059\u3002\uff08\u5185\u6d77\uff09<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">KiDS\u30d7\u30ed\u30b8\u30a7\u30af\u30c8\u306e\u3053\u308c\u304b\u3089<\/h4>\n\n\n\n<p>KiDS\u30d7\u30ed\u30b8\u30a7\u30af\u30c8\u306f\u300120\u5e74\u524d\u306b\u59cb\u307e\u308a\u3001\u4eca\u5e74\u304b\u3089\u95a2\u897f\u5927\u5b66\u304c\u65b0\u305f\u306b\u52a0\u308f\u308a\u307e\u3057\u305f\u3002\u79c1\u305f\u3061\u306f\u3053\u306e\u6d3b\u52d5\u309210\u5e74\u300120\u5e74\u3068\u672a\u6765\u3078\u3064\u306a\u3052\u3001\u3072\u3068\u308a\u3067\u3082\u591a\u304f\u306e\u547d\u3092\u5b88\u308b\u305f\u3081\u306b\u6b69\u307f\u7d9a\u3051\u307e\u3059\u3002<\/p>\n\n\n\n<p>\u3053\u306e\u30d6\u30ed\u30b0\u3092\u8aad\u3093\u3067\u5c11\u3057\u3067\u3082\u95a2\u5fc3\u3092\u6301\u3063\u3066\u304f\u3060\u3055\u3063\u305f\u65b9\u306f\u3001\u305c\u3072\u4e00\u5ea6\u5965\u6751\u30bc\u30df\u3092\u8a2a\u554f\u3057\u3066\u307f\u3066\u304f\u3060\u3055\u3044\u3002\u6700\u5f8c\u307e\u3067\u8aad\u3093\u3067\u3044\u305f\u3060\u304d\u3001\u3042\u308a\u304c\u3068\u3046\u3054\u3056\u3044\u307e\u3057\u305f\uff01<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u3053\u3093\u306b\u3061\u306f\uff01\u5965\u6751\u30bc\u30df3\u56de\u751f\u306e\u91d1\u6fa4\u60a0\u6a39\u3067\u3059\u3002\u79c1\u306f9\u67083\u65e5\u304b\u30891 &#8230;<\/p>\n","protected":false},"author":84,"featured_media":6424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11,9,3],"tags":[163,164],"class_list":["post-6463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11","category-9","category-fcss-blog","tag-taiyo-utsumi","tag-haruki-kanazawa"],"_links":{"self":[{"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/posts\/6463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/comments?post=6463"}],"version-history":[{"count":23,"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/posts\/6463\/revisions"}],"predecessor-version":[{"id":6541,"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/posts\/6463\/revisions\/6541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/media\/6424"}],"wp:attachment":[{"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/media?parent=6463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/categories?post=6463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wps.itc.kansai-u.ac.jp\/bosai\/wp-json\/wp\/v2\/tags?post=6463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}